{"id":31,"count":1,"description":"","link":"https:\/\/packlagi.com\/blog\/tag\/lokal\/","name":"lokal","slug":"lokal","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.2 (Yoast SEO v21.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>lokal Archives - Packlagi - Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/packlagi.com\/blog\/tag\/lokal\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"lokal Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/packlagi.com\/blog\/tag\/lokal\/\" \/>\n<meta property=\"og:site_name\" content=\"Packlagi - Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/packlagi.com\/blog\/tag\/lokal\/\",\"url\":\"https:\/\/packlagi.com\/blog\/tag\/lokal\/\",\"name\":\"lokal Archives - Packlagi - Blog\",\"isPartOf\":{\"@id\":\"https:\/\/packlagi.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/packlagi.com\/blog\/tag\/lokal\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/packlagi.com\/blog\/tag\/lokal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/packlagi.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"lokal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/packlagi.com\/blog\/#website\",\"url\":\"https:\/\/packlagi.com\/blog\/\",\"name\":\"Packlagi - Blog\",\"description\":\"Ide Packaging Menarik Bikin Customer Teetarik\",\"publisher\":{\"@id\":\"https:\/\/packlagi.com\/blog\/#organization\"},\"alternateName\":\"Packlagi - Artikerl dan Tips\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/packlagi.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\/\/packlagi.com\/blog\/#organization\",\"name\":\"Packlagi\",\"url\":\"https:\/\/packlagi.com\/blog\/\",\"logo\":{\"@id\":\"https:\/\/packlagi.com\/blog\/tag\/lokal\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\/\/packlagi.com\/blog\/tag\/lokal\/#local-main-organization-logo\"},\"sameAs\":[\"https:\/\/www.instagram.com\/packlagi\/\"],\"address\":{\"@id\":\"https:\/\/packlagi.com\/blog\/tag\/lokal\/#local-main-place-address\"},\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"PostalAddress\",\"@id\":\"https:\/\/packlagi.com\/blog\/tag\/lokal\/#local-main-place-address\",\"streetAddress\":\"Bendungan Hilir No 11, Tanah Abang\",\"addressLocality\":\"Jakarta Pusat\",\"postalCode\":\"10210\",\"addressRegion\":\"Jakarta\",\"addressCountry\":\"ID\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/packlagi.com\/blog\/tag\/lokal\/#local-main-organization-logo\",\"url\":\"https:\/\/packlagi.com\/blog\/wp-content\/uploads\/2023\/11\/favicon.ico\",\"contentUrl\":\"https:\/\/packlagi.com\/blog\/wp-content\/uploads\/2023\/11\/favicon.ico\",\"width\":16,\"height\":16,\"caption\":\"Packlagi\"}]}<\/script>\n<meta name=\"geo.placename\" content=\"Jakarta Pusat\" \/>\n<meta name=\"geo.region\" content=\"Indonesia\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"lokal Archives - Packlagi - Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/packlagi.com\/blog\/tag\/lokal\/","og_locale":"en_US","og_type":"article","og_title":"lokal Archives","og_url":"https:\/\/packlagi.com\/blog\/tag\/lokal\/","og_site_name":"Packlagi - Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/packlagi.com\/blog\/tag\/lokal\/","url":"https:\/\/packlagi.com\/blog\/tag\/lokal\/","name":"lokal Archives - Packlagi - Blog","isPartOf":{"@id":"https:\/\/packlagi.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/packlagi.com\/blog\/tag\/lokal\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/packlagi.com\/blog\/tag\/lokal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/packlagi.com\/blog\/"},{"@type":"ListItem","position":2,"name":"lokal"}]},{"@type":"WebSite","@id":"https:\/\/packlagi.com\/blog\/#website","url":"https:\/\/packlagi.com\/blog\/","name":"Packlagi - Blog","description":"Ide Packaging Menarik Bikin Customer Teetarik","publisher":{"@id":"https:\/\/packlagi.com\/blog\/#organization"},"alternateName":"Packlagi - Artikerl dan Tips","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/packlagi.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":["Organization","Place"],"@id":"https:\/\/packlagi.com\/blog\/#organization","name":"Packlagi","url":"https:\/\/packlagi.com\/blog\/","logo":{"@id":"https:\/\/packlagi.com\/blog\/tag\/lokal\/#local-main-organization-logo"},"image":{"@id":"https:\/\/packlagi.com\/blog\/tag\/lokal\/#local-main-organization-logo"},"sameAs":["https:\/\/www.instagram.com\/packlagi\/"],"address":{"@id":"https:\/\/packlagi.com\/blog\/tag\/lokal\/#local-main-place-address"},"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"PostalAddress","@id":"https:\/\/packlagi.com\/blog\/tag\/lokal\/#local-main-place-address","streetAddress":"Bendungan Hilir No 11, Tanah Abang","addressLocality":"Jakarta Pusat","postalCode":"10210","addressRegion":"Jakarta","addressCountry":"ID"},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/packlagi.com\/blog\/tag\/lokal\/#local-main-organization-logo","url":"https:\/\/packlagi.com\/blog\/wp-content\/uploads\/2023\/11\/favicon.ico","contentUrl":"https:\/\/packlagi.com\/blog\/wp-content\/uploads\/2023\/11\/favicon.ico","width":16,"height":16,"caption":"Packlagi"}]},"geo.placename":"Jakarta Pusat","geo.region":"Indonesia"},"_links":{"self":[{"href":"https:\/\/packlagi.com\/blog\/wp-json\/wp\/v2\/tags\/31","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/packlagi.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/packlagi.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/packlagi.com\/blog\/wp-json\/wp\/v2\/posts?tags=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}